{"id":45545,"date":"2025-07-04T12:37:05","date_gmt":"2025-07-04T10:37:05","guid":{"rendered":"https:\/\/bonsailab.com\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/"},"modified":"2025-10-28T13:27:17","modified_gmt":"2025-10-28T12:27:17","slug":"discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution","status":"publish","type":"post","link":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/","title":{"rendered":"Discover Xenium: Spatial gene expression analysis at single-cell resolution"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:30px;--awb-padding-bottom:20px;--awb-margin-top:49.9965px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1 blogintro\" style=\"--awb-font-size:16px;--awb-text-color:#001847;--awb-margin-right:50px;--awb-margin-left:50px;\"><p>Discover <strong>Xenium<\/strong>, the powerful spatial transcriptomics platform from 10x Genomics, designed to map gene expression at <strong>subcellular resolution<\/strong> while preserving tissue architecture. This seminar will provide an in-depth overview of the technology, its applications, and how it can be integrated into your research.<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-font-size:16px;--awb-text-color:#001847;--awb-margin-right:50px;--awb-margin-left:50px;\" id=\"blog-block\"><p>We will cover:<\/p>\n<ul>\n<li>What <strong>Xenium<\/strong> is and how it enables <strong>high-resolution spatial biology<\/strong><\/li>\n<li>A step-by-step breakdown of the <strong>Xenium workflow<\/strong>, from sample preparation to data generation<\/li>\n<li>Key considerations and best practices for <strong>sample preparation<\/strong><\/li>\n<li>Guidelines for <strong>custom and pre-designed panel selection<\/strong>, including strategies for optimizing <strong>panel design<\/strong> based on your research questions<\/li>\n<li>An introduction to <strong>data analysis and visualization<\/strong>, including how to interpret spatial expression maps and integrate them with other omics data<\/li>\n<\/ul>\n<p>At the end of the seminar, participants will have the opportunity to schedule <strong>one-to-one meetings<\/strong> with our specialists to discuss project-specific questions, experimental design, or technical details.<\/p>\n<p style=\"padding-left: 40px;\"><strong>Date: <\/strong>16th July<strong><br \/>\n<\/strong><strong>Time: <\/strong>9:00h<br \/>\n<strong>Location: IRB Barcelona.<br \/>\n<\/strong>\u00a0 \u00a0 TI Room 3. Edificio Torres (acceso por c\/Baldiri Reixac, 4-8).<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-45700 size-medium\" src=\"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-300x116.jpg\" alt=\"\" width=\"300\" height=\"116\" srcset=\"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-200x77.jpg 200w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-300x116.jpg 300w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-400x154.jpg 400w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-600x231.jpg 600w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-768x296.jpg 768w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-800x308.jpg 800w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5-1024x394.jpg 1024w, https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/IRBBarcelona-Logo-Horizontal-Color-5.jpg 1106w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-medium button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type fusion-has-button-gradient\" style=\"--button_accent_color:#ffffff;--button_accent_hover_color:#010051;--button_border_hover_color:#010051;--button_gradient_angle:180deg;--button_gradient_top_color:#022350;--button_gradient_bottom_color:var(--awb-custom15);--button_gradient_top_color_hover:var(--awb-color1);--button_gradient_bottom_color_hover:rgba(255,255,255,0.64);--button_typography-font-family:&quot;Montserrat&quot;;--button_typography-font-style:normal;--button_typography-font-weight:400;\" target=\"_self\" href=\"https:\/\/calendly.com\/elena-aranda-ixq\/1to1-meetings-iisgm-clone\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Optional One-to-One Meetings<\/span><\/a><\/div><div class=\"fusion-text fusion-text-3 fusion-text-no-margin\" style=\"--awb-font-size:16px;--awb-text-color:#001847;--awb-margin-top:10px;--awb-margin-right:50px;--awb-margin-bottom:30px;--awb-margin-left:50px;\" id=\"blog-block\"><p style=\"text-align: center;\">Whether you&#8217;re new to spatial biology or preparing to launch your first Xenium experiment, this session will offer <strong>valuable scientific and practical insights<\/strong>.<\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-medium button-custom fusion-button-default button-2 fusion-button-default-span fusion-button-default-type fusion-has-button-gradient\" style=\"--awb-margin-bottom:0px;--button_accent_color:#ffffff;--button_accent_hover_color:#010051;--button_border_hover_color:#010051;--button_gradient_angle:180deg;--button_gradient_top_color:#022350;--button_gradient_bottom_color:var(--awb-custom15);--button_gradient_top_color_hover:var(--awb-color1);--button_gradient_bottom_color_hover:rgba(255,255,255,0.64);--button_typography-font-family:&quot;Montserrat&quot;;--button_typography-font-style:normal;--button_typography-font-weight:400;\" target=\"_self\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf0rJPpY3gFm1sogzJQjkR8_EWT4zQGmWRVydap0y-5G7EOZw\/viewform\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Free Registration<\/span><\/a><\/div><div class=\"fusion-text fusion-text-4\" style=\"--awb-font-size:16px;--awb-text-color:#001847;--awb-margin-top:10px;--awb-margin-right:50px;--awb-margin-left:50px;\" id=\"blog-block\"><p style=\"text-align: center;\">(Limited spots \u2014 registration required)<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":45530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[194,196,253],"tags":[],"class_list":["post-45545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-pt-pt","category-genomica-pt-pt","category-10xgenomics-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discover Xenium: Spatial gene expression analysis at single-cell resolution - Bonsai Lab<\/title>\n<meta name=\"description\" content=\"We invite you to the Bonsai Technology Day event at the IBBTEC for those new to Single Cell &amp; Spatial technology and experienced 10x Genomics users.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discover Xenium: Spatial gene expression analysis at single-cell resolution - Bonsai Lab\" \/>\n<meta property=\"og:description\" content=\"We invite you to the Bonsai Technology Day event at the IBBTEC for those new to Single Cell &amp; Spatial technology and experienced 10x Genomics users.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonsai Lab\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T10:37:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T12:27:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/202507-Xenium3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"990\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BonsaiLab.com Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"BonsaiLab.com Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/\"},\"author\":{\"name\":\"BonsaiLab.com Admin\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#\\\/schema\\\/person\\\/add0096ceff54b5330e7c05730d687b3\"},\"headline\":\"Discover Xenium: Spatial gene expression analysis at single-cell resolution\",\"datePublished\":\"2025-07-04T10:37:05+00:00\",\"dateModified\":\"2025-10-28T12:27:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/\"},\"wordCount\":8115,\"publisher\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsailab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/202507-Xenium3.jpg\",\"articleSection\":[\"Actualidad\",\"Gen\u00f3mica\",\"10xGenomics\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/\",\"url\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/\",\"name\":\"Discover Xenium: Spatial gene expression analysis at single-cell resolution - Bonsai Lab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonsailab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/202507-Xenium3.jpg\",\"datePublished\":\"2025-07-04T10:37:05+00:00\",\"dateModified\":\"2025-10-28T12:27:17+00:00\",\"description\":\"We invite you to the Bonsai Technology Day event at the IBBTEC for those new to Single Cell & Spatial technology and experienced 10x Genomics users.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonsailab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/202507-Xenium3.jpg\",\"contentUrl\":\"https:\\\/\\\/bonsailab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/202507-Xenium3.jpg\",\"width\":1900,\"height\":990},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bonsailab.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discover Xenium: Spatial gene expression analysis at single-cell resolution\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#website\",\"url\":\"https:\\\/\\\/bonsailab.com\\\/\",\"name\":\"Bonsai Lab\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonsailab.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#organization\",\"name\":\"BonsaiLab\",\"url\":\"https:\\\/\\\/bonsailab.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bonsailab.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo_bonsailab.png\",\"contentUrl\":\"https:\\\/\\\/bonsailab.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo_bonsailab.png\",\"width\":280,\"height\":40,\"caption\":\"BonsaiLab\"},\"image\":{\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bonsai-advanced-technologies-s-l-\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCv7xfNvsrS9NADlz0yQFWGA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonsailab.com\\\/#\\\/schema\\\/person\\\/add0096ceff54b5330e7c05730d687b3\",\"name\":\"BonsaiLab.com Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd8813b5fa80e8c63d6ea29ba8f27ddc2618160355ad9b7941b0a378884421d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd8813b5fa80e8c63d6ea29ba8f27ddc2618160355ad9b7941b0a378884421d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd8813b5fa80e8c63d6ea29ba8f27ddc2618160355ad9b7941b0a378884421d5?s=96&d=mm&r=g\",\"caption\":\"BonsaiLab.com Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discover Xenium: Spatial gene expression analysis at single-cell resolution - Bonsai Lab","description":"We invite you to the Bonsai Technology Day event at the IBBTEC for those new to Single Cell & Spatial technology and experienced 10x Genomics users.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/","og_locale":"pt_PT","og_type":"article","og_title":"Discover Xenium: Spatial gene expression analysis at single-cell resolution - Bonsai Lab","og_description":"We invite you to the Bonsai Technology Day event at the IBBTEC for those new to Single Cell & Spatial technology and experienced 10x Genomics users.","og_url":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/","og_site_name":"Bonsai Lab","article_published_time":"2025-07-04T10:37:05+00:00","article_modified_time":"2025-10-28T12:27:17+00:00","og_image":[{"width":1900,"height":990,"url":"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/202507-Xenium3.jpg","type":"image\/jpeg"}],"author":"BonsaiLab.com Admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"BonsaiLab.com Admin","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#article","isPartOf":{"@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/"},"author":{"name":"BonsaiLab.com Admin","@id":"https:\/\/bonsailab.com\/#\/schema\/person\/add0096ceff54b5330e7c05730d687b3"},"headline":"Discover Xenium: Spatial gene expression analysis at single-cell resolution","datePublished":"2025-07-04T10:37:05+00:00","dateModified":"2025-10-28T12:27:17+00:00","mainEntityOfPage":{"@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/"},"wordCount":8115,"publisher":{"@id":"https:\/\/bonsailab.com\/#organization"},"image":{"@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/202507-Xenium3.jpg","articleSection":["Actualidad","Gen\u00f3mica","10xGenomics"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/","url":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/","name":"Discover Xenium: Spatial gene expression analysis at single-cell resolution - Bonsai Lab","isPartOf":{"@id":"https:\/\/bonsailab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#primaryimage"},"image":{"@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#primaryimage"},"thumbnailUrl":"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/202507-Xenium3.jpg","datePublished":"2025-07-04T10:37:05+00:00","dateModified":"2025-10-28T12:27:17+00:00","description":"We invite you to the Bonsai Technology Day event at the IBBTEC for those new to Single Cell & Spatial technology and experienced 10x Genomics users.","breadcrumb":{"@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#primaryimage","url":"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/202507-Xenium3.jpg","contentUrl":"https:\/\/bonsailab.com\/wp-content\/uploads\/2025\/07\/202507-Xenium3.jpg","width":1900,"height":990},{"@type":"BreadcrumbList","@id":"https:\/\/bonsailab.com\/pt-pt\/discover-xenium-spatial-gene-expression-analysis-at-single-cell-resolution\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bonsailab.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Discover Xenium: Spatial gene expression analysis at single-cell resolution"}]},{"@type":"WebSite","@id":"https:\/\/bonsailab.com\/#website","url":"https:\/\/bonsailab.com\/","name":"Bonsai Lab","description":"","publisher":{"@id":"https:\/\/bonsailab.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonsailab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/bonsailab.com\/#organization","name":"BonsaiLab","url":"https:\/\/bonsailab.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/bonsailab.com\/#\/schema\/logo\/image\/","url":"https:\/\/bonsailab.com\/wp-content\/uploads\/2018\/07\/logo_bonsailab.png","contentUrl":"https:\/\/bonsailab.com\/wp-content\/uploads\/2018\/07\/logo_bonsailab.png","width":280,"height":40,"caption":"BonsaiLab"},"image":{"@id":"https:\/\/bonsailab.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bonsai-advanced-technologies-s-l-\/","https:\/\/www.youtube.com\/channel\/UCv7xfNvsrS9NADlz0yQFWGA"]},{"@type":"Person","@id":"https:\/\/bonsailab.com\/#\/schema\/person\/add0096ceff54b5330e7c05730d687b3","name":"BonsaiLab.com Admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/bd8813b5fa80e8c63d6ea29ba8f27ddc2618160355ad9b7941b0a378884421d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd8813b5fa80e8c63d6ea29ba8f27ddc2618160355ad9b7941b0a378884421d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd8813b5fa80e8c63d6ea29ba8f27ddc2618160355ad9b7941b0a378884421d5?s=96&d=mm&r=g","caption":"BonsaiLab.com Admin"}}]}},"_links":{"self":[{"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/posts\/45545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=45545"}],"version-history":[{"count":3,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/posts\/45545\/revisions"}],"predecessor-version":[{"id":48609,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/posts\/45545\/revisions\/48609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/media\/45530"}],"wp:attachment":[{"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=45545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=45545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonsailab.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=45545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}